{"id":1190,"date":"2021-07-15T12:32:00","date_gmt":"2021-07-15T12:32:00","guid":{"rendered":"https:\/\/hyperbate.fr\/whatever\/?p=1190"},"modified":"2022-03-17T15:08:27","modified_gmt":"2022-03-17T15:08:27","slug":"miroir-noir","status":"publish","type":"post","link":"https:\/\/hyperbate.fr\/whatever\/2021\/07\/15\/miroir-noir\/","title":{"rendered":"Miroir noir"},"content":{"rendered":"\n<p>Le nom de la s\u00e9rie <em>Black Mirror<\/em> fait r\u00e9f\u00e9rence aux \u00e9crans des appareils num\u00e9riques, et notamment des smartphones, mais ce nom a aussi eu une autre signification. J&rsquo;ignore totalement si le lien est conscient de la part de Charlie Brooker, le cr\u00e9ateur de la s\u00e9rie.<\/p>\n\n\n\n<p>Le <em>Miroir noir<\/em>, aussi appel\u00e9 <em>Miroir de Claude<\/em> (<em>Claude glass<\/em>, en anglais), est un instrument d&rsquo;observation employ\u00e9 par des peintres paysagistes de la fin du XVIIIe si\u00e8cle. Le pr\u00e9nom Claude fait r\u00e9f\u00e9rence \u00e0 Claude Gell\u00e9e, dit le Lorrain, peintre du XVIIe si\u00e8cle, qui n&rsquo;a pourtant sans doute jamais utilis\u00e9 un tel appareil lui-m\u00eame, mais dont l&rsquo;\u0153uvre a eu une influence d\u00e9cisive sur les paysagistes anglais des XVIII-XIXe si\u00e8cles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1.png\"><img decoding=\"async\" width=\"938\" height=\"933\" src=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1.png\" alt=\"\" class=\"wp-image-1205\" srcset=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1.png 938w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1-300x298.png 300w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1-150x150.png 150w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-1-768x764.png 768w\" sizes=\"(max-width: 938px) 100vw, 938px\" \/><\/a><\/figure>\n\n\n\n<p>L&rsquo;appareil est un miroir ench\u00e2ss\u00e9 dans un boitier. C&rsquo;est un miroir l\u00e9g\u00e8rement convexe et teint\u00e9 au noir de fum\u00e9e. On l&rsquo;utilise pour regarder le paysage auquel au tourne le dos. Il permet de d\u00e9finir un cadrage, et il modifie le contraste et les couleurs de la sc\u00e8ne, aidant l&rsquo;artiste \u00e0 se concentrer sur l&rsquo;essentiel. <br>Cet appareil n&rsquo;a pas \u00e9t\u00e9 seulement populaire aupr\u00e8s des peintres, c&rsquo;\u00e9tait aussi un accessoire commun pour les touristes. \u00c0 cette \u00e9poque, le tourisme naissant ne concernait qu&rsquo;un nombre tr\u00e8s r\u00e9duit de gens de la bonne soci\u00e9t\u00e9 ayant le temps et les moyens de fl\u00e2ner, et dont le but \u00e9tait certes de profiter du \u00ab bon air \u00bb, mais aussi de voir : voir les massifs des Pyr\u00e9n\u00e9es, les glaciers des Alpes, voir les ruines antiques, etc. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image.png\"><img decoding=\"async\" width=\"800\" height=\"844\" src=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image.png\" alt=\"\" class=\"wp-image-1201\" srcset=\"https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image.png 800w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-284x300.png 284w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-768x810.png 768w, https:\/\/hyperbate.fr\/whatever\/files\/2022\/03\/image-142x150.png 142w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p>Les voyageurs \u00e9taient assist\u00e9s de plusieurs dispositifs pour mieux observer et pour savoir quoi regarder. Ces dispositifs pouvaient \u00eatre portables (lunettes, jumelles, miroir de Claude, mais aussi cartes et guides touristiques) ou fix\u00e9s sur les lieux m\u00eames du paysage \u00e0 contempler, ou \u00e0 proximit\u00e9 (plans, tables d&rsquo;orientation, t\u00e9lescopes fixes, tours d&rsquo;observation, panoramas,&#8230;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nom de la s\u00e9rie Black Mirror fait r\u00e9f\u00e9rence aux \u00e9crans des appareils num\u00e9riques, et notamment des smartphones, mais ce nom a aussi eu une autre signification. J&rsquo;ignore totalement si le lien est conscient de la part de Charlie Brooker, le cr\u00e9ateur de la s\u00e9rie. Le Miroir noir, aussi appel\u00e9 Miroir de Claude (Claude glass, &hellip; <a href=\"https:\/\/hyperbate.fr\/whatever\/2021\/07\/15\/miroir-noir\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Miroir noir<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-1190","post","type-post","status-publish","format-standard","hentry","category-dessin"],"_links":{"self":[{"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":2,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"predecessor-version":[{"id":1212,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/posts\/1190\/revisions\/1212"}],"wp:attachment":[{"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hyperbate.fr\/whatever\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}