{"id":17,"count":1,"description":"","link":"https:\/\/hyperbate.fr\/dezone\/tag\/sculpture\/","name":"sculpture","slug":"sculpture","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hyperbate.fr\/dezone\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hyperbate.fr\/dezone\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hyperbate.fr\/dezone\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hyperbate.fr\/dezone\/wp-json\/wp\/v2\/posts?tags=17"},{"href":"https:\/\/hyperbate.fr\/dezone\/wp-json\/wp\/v2\/pmb_content?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}